{"id":8745,"date":"2017-03-11T12:30:03","date_gmt":"2017-03-11T11:30:03","guid":{"rendered":"http:\/\/www.vorbei-ev.de\/wwwa\/?p=8745"},"modified":"2021-03-06T12:59:35","modified_gmt":"2021-03-06T11:59:35","slug":"vereinsaktivitaeten-im-februar-2017","status":"publish","type":"post","link":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/","title":{"rendered":"Vereinsaktivit\u00e4ten im Februar 2017"},"content":{"rendered":"<h2>Im Februar 2017 wurde unser Vereinsarbeit durch ein besonderes Ereignis gepr\u00e4gt: Wir feierten unser 10-j\u00e4hriges Vereinsjubil\u00e4um!!!<\/h2>\n<p>In unserem Gr\u00fcndungsprotokoll wird der Beginn unserer Vereinsgeschichte mit den folgenden Worten sachlich dokumentiert (Anschrift unkenntlich gemacht):<\/p>\n<table>\n<tbody>\n<tr>\n<td><\/td>\n<td style=\"width: 80%;\">Am 20.01.2007 um 15:00 Uhr kamen in der XXXXXXXXXXX, 30974 Wennigsen acht Personen zusammen (Anwesenheitsliste ist beigef\u00fcgt), um die Gr\u00fcndung des Vereins \u201eVorbei\u201c zu beschlie\u00dfen.<\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Ab diesem Zeitpunkt hat sich unsere Vereinsgeschichte in einer Art und<br \/>\nWeise entwickelt, mit der wir damals auf unserer Gr\u00fcndungsversammlung<br \/>\nnicht gerechnet hatten. Wir m\u00f6chten an dieser Stelle auch noch einmal<br \/>\nauf unsere monatlich erscheinenden T\u00e4tigkeitsberichte hinweisen. Seit<br \/>\nder Vereinsgr\u00fcndung haben wir unsere Vereinsarbeit dokumentiert und in unserer Internetpr\u00e4sentation ver\u00f6ffentlicht. Wir haben die Meilensteine unserer Vereinsgeschichte in einem kurzen \u00dcberblick zusammengefasst:<\/p>\n<p>Kurz nach der Vereinsgr\u00fcndung wurde von unserem Verein eine als Denkmal<br \/>\neingestufte Liegenschaft in der Region Hannover betreut, die uns von<br \/>\nder Bundesagentur f\u00fcr Immobilienaufgaben (BImA) vertraglich und unbefristet \u00fcberlassen wurde. Es handelte sich dabei um die ehemalige Grundnetzschalt- und Vermittlungsstelle der Bundeswehr (GSVBw 21) in Springe\/L\u00fcdersen. In dieser Liegenschaft wurden die noch vorhandenen Einrichtungen, wie auch die Geb\u00e4ude und Au\u00dfenanlagen, von unseren ehrenamtlichen Mitgliedern restauriert. Ziel sollte die Einrichtung eines Museums sein. Das Gesamterscheinungsbild der Liegenschaft wurde ann\u00e4hernd in den Originalzustand versetzt, um dadurch den musealen Charakter des Objektes zu festigen. Leider wurde diese Liegenschaft an einen gewerblichen Interessenten verkauft und stand unserem Verein nicht mehr zur Verf\u00fcgung. Wir haben dieser Anlage ein virtuelles Museum gewidmet, das \u00fcber unsere Internetpr\u00e4senz oder direkt unter http:\/\/www.gsvbw21.de erreicht werden kann.<\/p>\n<figure id=\"attachment_376\" aria-describedby=\"caption-attachment-376\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-376 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01.jpg\" alt=\"Im Aufenthaltsraum der GSVBw 22: Anl\u00e4sslich unseres Vereinsjubil\u00e4ums wurden Speisekarten angefertigt.\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01-400x267.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01-768x512.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-376\" class=\"wp-caption-text\">Im Aufenthaltsraum der GSVBw 22: Anl\u00e4sslich unseres Vereinsjubil\u00e4ums wurden Speisekarten angefertigt.<\/figcaption><\/figure>\n<figure id=\"attachment_380\" aria-describedby=\"caption-attachment-380\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-380 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_05.jpg\" alt=\"Unsere Jubil\u00e4umsfeier beginnt am Nachmittag mit einer Kaffee- und Kuchentafel.\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_05.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_05-400x267.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_05-768x512.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-380\" class=\"wp-caption-text\">Unsere Jubil\u00e4umsfeier beginnt am Nachmittag mit einer Kaffee- und Kuchentafel.<\/figcaption><\/figure>\n<figure id=\"attachment_381\" aria-describedby=\"caption-attachment-381\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-381 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_06.jpg\" alt=\"... und endet erst zu sp\u00e4ter Stunde.\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_06.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_06-400x267.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_06-768x512.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-381\" class=\"wp-caption-text\">&#8230; und endet erst zu sp\u00e4ter Stunde.<\/figcaption><\/figure>\n<p style=\"text-align: left;\">Unser Verein Vorbei e.V. wurde am 20.01.2007 im Ort Wennigsen in der Region Hannover gegr\u00fcndet. Der Vorbei e.V. im Vereinsregister des Amtsgerichtes Hannover registriert. Das zust\u00e4ndige Finanzamt Hannover-Land I hat den Vorbei e.V. als gemeinn\u00fctzig anerkannt.<\/p>\n<h2>Museumsbunker Hannover: Reparaturarbeiten im Innenbereich<\/h2>\n<p>Auch wenn unsere Vereinsarbeit im Februar haupts\u00e4chlich durch die Feierlichkeiten zum 10-j\u00e4hrigen Vereinsjubil\u00e4um gepr\u00e4gt wurde, besch\u00e4ftigten wir uns weiterhin mit der Restauration und Instandsetzung unserer Vereinsanlagen. Neben hochinteressierten G\u00e4sten, die unsere Grundnetzschaltvermittlungsstelle der Bundeswehr in Elmlohe (GSVBw 22) und die ehemalige Zivilschutzanlage in Hannover-Ricklingen (Museumsbunker Hannover) besuchten, f\u00fchrten wir verschiedene Reparaturarbeiten durch. Im Museumsbunker Hannover ist uns ein Thermostat aufgefallen, der sich vermutlich durch mechanische Einwirkungen nicht mehr in seiner vorgesehenen Lage befand. Der Thermostat wurde im Rohrleitungssystem der K\u00fchlwasserversorgung eingesetzt und ist ein Bestandteil der Betriebs\u00fcberwachung. Mit Hilfe dieses Thermostats wurde ein Alarmsignal eingeschaltet, falls die Temperatur des K\u00fchlwassers der Dieselmaschinens\u00e4tze einen eingestellten Temperaturwert \u00fcberschritten h\u00e4tte. Wir haben den Thermostat ausgebaut, gereinigt und gerichtet. Anschlie\u00dfend wurde das Bauteil wieder installiert.<\/p>\n<figure id=\"attachment_377\" aria-describedby=\"caption-attachment-377\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-377 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_02.jpg\" alt=\"Nicht mehr in korrekter Lage: Ein Thermostat im K\u00fchlwasserkreislauf.\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_02.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_02-400x267.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_02-768x512.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-377\" class=\"wp-caption-text\">Nicht mehr in korrekter Lage: Ein Thermostat im K\u00fchlwasserkreislauf.<\/figcaption><\/figure>\n<figure id=\"attachment_378\" aria-describedby=\"caption-attachment-378\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-378 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_03.jpg\" alt=\"Der Thermostat wurde ausgebaut, gereinigt und neu ausgerichtet.\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_03.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_03-400x267.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_03-768x512.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-378\" class=\"wp-caption-text\">Der Thermostat wurde ausgebaut, gereinigt und neu ausgerichtet.<\/figcaption><\/figure>\n<figure id=\"attachment_379\" aria-describedby=\"caption-attachment-379\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-379 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_04.jpg\" alt=\"Sitzt wieder in richtiger Position: Der Thermostat im Rohrsystem des K\u00fchlwasserkreislaufes.\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_04.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_04-400x267.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_04-768x512.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-379\" class=\"wp-caption-text\">Sitzt wieder in richtiger Position: Der Thermostat im Rohrsystem des K\u00fchlwasserkreislaufes.<\/figcaption><\/figure>\n<p>Der K\u00fchlwasserkreislauf dient zur K\u00fchlung der beiden Dieselmaschinens\u00e4tze. \u00dcber verschiedene W\u00e4rmetauscher kann das K\u00fchlwasser dazu verwendet werden, Luft in der Bel\u00fcftungsanlage oder Wasser f\u00fcr die Dekontaminationsduschen zu erw\u00e4rmen. Weiterhin ist ein Wasserk\u00fchler im Filteranbau zum Herunterk\u00fchlen des Wassers vorgesehen.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left shariff-buttonstretch\" data-services=\"facebook\" data-url=\"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/\" data-timestamp=\"1615035575\" data-backendurl=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/shariff\/v1\/share_counts?\"><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.vorbei-ev.de%2Fwwwa%2F2017%2F03%2F11%2Fvereinsaktivitaeten-im-februar-2017%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.vorbei-ev.de%2Fwwwa%2F2017%2F03%2F11%2Fvereinsaktivitaeten-im-februar-2017%2F&text=Vereinsaktivit%C3%A4ten%20im%20Februar%202017\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.vorbei-ev.de%2Fwwwa%2F2017%2F03%2F11%2Fvereinsaktivitaeten-im-februar-2017%2F%20Vereinsaktivit%C3%A4ten%20im%20Februar%202017\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button telegram shariff-nocustomcolor\" style=\"background-color:#4084A6\"><a href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.vorbei-ev.de%2Fwwwa%2F2017%2F03%2F11%2Fvereinsaktivitaeten-im-februar-2017%2F&text=Vereinsaktivit%C3%A4ten%20im%20Februar%202017\" title=\"Bei Telegram teilen\" aria-label=\"Bei Telegram teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0088cc; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#0088cc\" d=\"M30.8 6.5l-4.5 21.4c-.3 1.5-1.2 1.9-2.5 1.2L16.9 24l-3.3 3.2c-.4.4-.7.7-1.4.7l.5-7L25.5 9.2c.6-.5-.1-.8-.9-.3l-15.8 10L2 16.7c-1.5-.5-1.5-1.5.3-2.2L28.9 4.3c1.3-.5 2.3.3 1.9 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Im Februar 2017 wurde unser Vereinsarbeit durch ein besonderes Ereignis gepr\u00e4gt: Wir feierten unser 10-j\u00e4hriges Vereinsjubil\u00e4um!!! In unserem Gr\u00fcndungsprotokoll wird der Beginn unserer Vereinsgeschichte mit den folgenden Worten sachlich dokumentiert (Anschrift unkenntlich gemacht): Am 20.01.2007 um 15:00 Uhr kamen in der XXXXXXXXXXX, 30974 Wennigsen acht Personen zusammen (Anwesenheitsliste ist beigef\u00fcgt), um die Gr\u00fcndung des Vereins &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eVereinsaktivit\u00e4ten im Februar 2017\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":376,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-8745","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-20","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vereinsaktivit\u00e4ten im Februar 2017 - Vorbei e.V.<\/title>\n<meta name=\"description\" content=\"Im Februar 2017 wurde unser Vereinsarbeit durch ein besonderes Ereignis gepr\u00e4gt: Wir feierten unser 10-j\u00e4hriges Vereinsjubil\u00e4um. Unser Verein Vorbei e.V. wurde am 20.01.2007 im Ort Wennigsen in der Region Hannover gegr\u00fcndet. Der Vorbei e.V. im Vereinsregister des Amtsgerichtes Hannover registriert. Das zust\u00e4ndige Finanzamt Hannover-Land I hat den Vorbei e.V. als gemeinn\u00fctzig anerkannt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vereinsaktivit\u00e4ten im Februar 2017 - Vorbei e.V.\" \/>\n<meta property=\"og:description\" content=\"Im Februar 2017 wurde unser Vereinsarbeit durch ein besonderes Ereignis gepr\u00e4gt: Wir feierten unser 10-j\u00e4hriges Vereinsjubil\u00e4um. Unser Verein Vorbei e.V. wurde am 20.01.2007 im Ort Wennigsen in der Region Hannover gegr\u00fcndet. Der Vorbei e.V. im Vereinsregister des Amtsgerichtes Hannover registriert. Das zust\u00e4ndige Finanzamt Hannover-Land I hat den Vorbei e.V. als gemeinn\u00fctzig anerkannt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Vorbei e.V.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/107150626035606\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-11T11:30:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-06T11:59:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lars Knauer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lars Knauer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/\"},\"author\":{\"name\":\"Lars Knauer\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#\\\/schema\\\/person\\\/73a85b6f1e47d7e120f5469e01829e53\"},\"headline\":\"Vereinsaktivit\u00e4ten im Februar 2017\",\"datePublished\":\"2017-03-11T11:30:03+00:00\",\"dateModified\":\"2021-03-06T11:59:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/\"},\"wordCount\":601,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/image2017-02_01.jpg\",\"articleSection\":[\"2017\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/\",\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/\",\"name\":\"Vereinsaktivit\u00e4ten im Februar 2017 - Vorbei e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/image2017-02_01.jpg\",\"datePublished\":\"2017-03-11T11:30:03+00:00\",\"dateModified\":\"2021-03-06T11:59:35+00:00\",\"description\":\"Im Februar 2017 wurde unser Vereinsarbeit durch ein besonderes Ereignis gepr\u00e4gt: Wir feierten unser 10-j\u00e4hriges Vereinsjubil\u00e4um. Unser Verein Vorbei e.V. wurde am 20.01.2007 im Ort Wennigsen in der Region Hannover gegr\u00fcndet. Der Vorbei e.V. im Vereinsregister des Amtsgerichtes Hannover registriert. Das zust\u00e4ndige Finanzamt Hannover-Land I hat den Vorbei e.V. als gemeinn\u00fctzig anerkannt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/image2017-02_01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/image2017-02_01.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2017\\\/03\\\/11\\\/vereinsaktivitaeten-im-februar-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vereinsaktivit\u00e4ten im Februar 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#website\",\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/\",\"name\":\"Vorbei e.V.\",\"description\":\"Dokumentation und Erhalt zeitgeschichtlicher Bauwerke\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#organization\",\"name\":\"Vorbei e.V.\",\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Logo_schwarz_640px.png\",\"contentUrl\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Logo_schwarz_640px.png\",\"width\":640,\"height\":120,\"caption\":\"Vorbei e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/107150626035606\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#\\\/schema\\\/person\\\/73a85b6f1e47d7e120f5469e01829e53\",\"name\":\"Lars Knauer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g\",\"caption\":\"Lars Knauer\"},\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/author\\\/lars\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vereinsaktivit\u00e4ten im Februar 2017 - Vorbei e.V.","description":"Im Februar 2017 wurde unser Vereinsarbeit durch ein besonderes Ereignis gepr\u00e4gt: Wir feierten unser 10-j\u00e4hriges Vereinsjubil\u00e4um. Unser Verein Vorbei e.V. wurde am 20.01.2007 im Ort Wennigsen in der Region Hannover gegr\u00fcndet. Der Vorbei e.V. im Vereinsregister des Amtsgerichtes Hannover registriert. Das zust\u00e4ndige Finanzamt Hannover-Land I hat den Vorbei e.V. als gemeinn\u00fctzig anerkannt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/","og_locale":"de_DE","og_type":"article","og_title":"Vereinsaktivit\u00e4ten im Februar 2017 - Vorbei e.V.","og_description":"Im Februar 2017 wurde unser Vereinsarbeit durch ein besonderes Ereignis gepr\u00e4gt: Wir feierten unser 10-j\u00e4hriges Vereinsjubil\u00e4um. Unser Verein Vorbei e.V. wurde am 20.01.2007 im Ort Wennigsen in der Region Hannover gegr\u00fcndet. Der Vorbei e.V. im Vereinsregister des Amtsgerichtes Hannover registriert. Das zust\u00e4ndige Finanzamt Hannover-Land I hat den Vorbei e.V. als gemeinn\u00fctzig anerkannt.","og_url":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/","og_site_name":"Vorbei e.V.","article_publisher":"https:\/\/www.facebook.com\/groups\/107150626035606\/","article_published_time":"2017-03-11T11:30:03+00:00","article_modified_time":"2021-03-06T11:59:35+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01.jpg","type":"image\/jpeg"}],"author":"Lars Knauer","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01.jpg","twitter_misc":{"Verfasst von":"Lars Knauer","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/#article","isPartOf":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/"},"author":{"name":"Lars Knauer","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#\/schema\/person\/73a85b6f1e47d7e120f5469e01829e53"},"headline":"Vereinsaktivit\u00e4ten im Februar 2017","datePublished":"2017-03-11T11:30:03+00:00","dateModified":"2021-03-06T11:59:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/"},"wordCount":601,"publisher":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#organization"},"image":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01.jpg","articleSection":["2017"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/","url":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/","name":"Vereinsaktivit\u00e4ten im Februar 2017 - Vorbei e.V.","isPartOf":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/#primaryimage"},"image":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01.jpg","datePublished":"2017-03-11T11:30:03+00:00","dateModified":"2021-03-06T11:59:35+00:00","description":"Im Februar 2017 wurde unser Vereinsarbeit durch ein besonderes Ereignis gepr\u00e4gt: Wir feierten unser 10-j\u00e4hriges Vereinsjubil\u00e4um. Unser Verein Vorbei e.V. wurde am 20.01.2007 im Ort Wennigsen in der Region Hannover gegr\u00fcndet. Der Vorbei e.V. im Vereinsregister des Amtsgerichtes Hannover registriert. Das zust\u00e4ndige Finanzamt Hannover-Land I hat den Vorbei e.V. als gemeinn\u00fctzig anerkannt.","breadcrumb":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/#primaryimage","url":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01.jpg","contentUrl":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/image2017-02_01.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2017\/03\/11\/vereinsaktivitaeten-im-februar-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.vorbei-ev.de\/wwwa\/"},{"@type":"ListItem","position":2,"name":"Vereinsaktivit\u00e4ten im Februar 2017"}]},{"@type":"WebSite","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#website","url":"https:\/\/www.vorbei-ev.de\/wwwa\/","name":"Vorbei e.V.","description":"Dokumentation und Erhalt zeitgeschichtlicher Bauwerke","publisher":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vorbei-ev.de\/wwwa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#organization","name":"Vorbei e.V.","url":"https:\/\/www.vorbei-ev.de\/wwwa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#\/schema\/logo\/image\/","url":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/04\/Logo_schwarz_640px.png","contentUrl":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/04\/Logo_schwarz_640px.png","width":640,"height":120,"caption":"Vorbei e.V."},"image":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/107150626035606\/"]},{"@type":"Person","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#\/schema\/person\/73a85b6f1e47d7e120f5469e01829e53","name":"Lars Knauer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g","caption":"Lars Knauer"},"url":"https:\/\/www.vorbei-ev.de\/wwwa\/author\/lars\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/posts\/8745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/comments?post=8745"}],"version-history":[{"count":1,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/posts\/8745\/revisions"}],"predecessor-version":[{"id":8746,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/posts\/8745\/revisions\/8746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/media\/376"}],"wp:attachment":[{"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/media?parent=8745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/categories?post=8745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/tags?post=8745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}