{"id":8650,"date":"2014-01-11T13:30:19","date_gmt":"2014-01-11T12:30:19","guid":{"rendered":"http:\/\/www.vorbei-ev.de\/wwwa\/?p=8650"},"modified":"2021-03-01T19:37:41","modified_gmt":"2021-03-01T18:37:41","slug":"vereinsaktivitaeten-im-dezember-2013","status":"publish","type":"post","link":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/","title":{"rendered":"Vereinsaktivit\u00e4ten im Dezember 2013"},"content":{"rendered":"<h1>Informations-Faltblatt \u00fcber das Projekt &#8222;Museumsbunker Hannover&#8220; verf\u00fcgbar<\/h1>\n<p>Aufgrund h\u00e4ufiger Nachfragen haben wir ein Informationsfaltblatt f\u00fcr unser Projekt &#8222;Museumsbunker Hannover&#8220; erstellt. Das Blatt informiert \u00fcber den Projekthintergrund und verdeutlicht die Besonderheiten der Zivilschutzanlage Hannover-Ricklingen. Weiterhin gibt es Eckdaten zu unserem gemeinn\u00fctzigen Verein und zu weiteren Vereinsprojekten.<\/p>\n<p>Das Informationsfaltblatt liegt zur Mitnahme in unseren Vereinsanlagen aus. Auch ein Download im PDF-Format ist \u00fcber das untenstehende Bild sowie \u00fcber die Fu\u00dfzeile m\u00f6glich.<\/p>\n<figure id=\"attachment_264\" aria-describedby=\"caption-attachment-264\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/flyer_hannover_low.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-264 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/flyer_hannover_400.jpg\" alt=\"\" width=\"400\" height=\"270\" \/><\/a><figcaption id=\"caption-attachment-264\" class=\"wp-caption-text\">Informationsfaltblatt &#8222;Museumsbunker Hannover&#8220;.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h1>Bergung weiterer Exponate f\u00fcr unsere geplante Bel\u00fcftungsger\u00e4te- und Raumfilter-Ausstellung<\/h1>\n<p>Wir berichteten bereits im Oktober \u00fcber unsere Planungen, in der Zivilschutzanlage Hannover-Ricklingen eine Sammlung verschiedener Schutzraum-Bel\u00fcftungsger\u00e4te aufzubauen. Zusammen mit unterschiedlichen Raumfiltermodellen soll so die Entwicklung dieser Ger\u00e4te anschaulich aufgezeigt werden. Im Dezember haben wir in enger Abstimmung mit der Bundesanstalt f\u00fcr Immobilienaufgaben (Bima) eine aufw\u00e4ndige Materialbergung auf einem ehemaligen Kasernengel\u00e4nde in der Landeshauptstadt Hannover durchgef\u00fchrt. Dabei konnten wir aus einem Keller-Schutzraum ein vollst\u00e4ndiges Bel\u00fcftungsger\u00e4t sowie verschiedene Raumfiltertonnen bergen. Das hohe Gewicht des Bel\u00fcftungsger\u00e4tes erschwerte die Bergung erheblich, so dass das Ger\u00e4t zun\u00e4chst zerlegt werden musste. Wir bedanken uns an dieser Stelle noch einmal ganz besonders bei der Bundesanstalt f\u00fcr Immobilienaufgaben f\u00fcr die Unterst\u00fctzung unserer ehrenamtlichen und gemeinn\u00fctzigen Vereinsarbeit!<\/p>\n<figure id=\"attachment_3865\" aria-describedby=\"caption-attachment-3865\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3865 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03-400x267.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03-768x512.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-3865\" class=\"wp-caption-text\">Die Raumfilter in den Gr\u00f6\u00dfen R3, R1,5 und R10 (von links nach rechts) werden zur Anschauung aufgearbeitet.<\/figcaption><\/figure>\n<figure id=\"attachment_3866\" aria-describedby=\"caption-attachment-3866\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3866 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_04.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_04.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_04-400x267.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_04-768x512.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-3866\" class=\"wp-caption-text\">Das Schutzraum-Bel\u00fcftungsger\u00e4t musste aufgrund des hohen Gewichtes zerlegt werden.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h1>Neu im Dokumentationsbereich: Beitrag \u00fcber die GSVBw 45 Jesberg<\/h1>\n<p>Die GSVBw 45 stellt eine Besonderheit dar, da sie angemietete Betriebsr\u00e4ume in einer Verst\u00e4rkerstelle der Deutschen Bundespost (DBP) nutzte. Durch dieses Alleinstellungsmerkmal unterschied sich die GSVBw 45 deutlich von den \u00fcbrigen Grundnetzschalt- und Vermittlungsstellen der Bundeswehr, die im Zuge von Sonderinfrastruktur-Bauma\u00dfnahmen errichtet wurden.<\/p>\n<p>Wir haben einen Informationsbeitrag \u00fcber die GSVBw 45 Jesberg erstellt, und in unserem Dokumentationsbereich eingeordnet.<\/p>\n<figure id=\"attachment_246\" aria-describedby=\"caption-attachment-246\" style=\"width: 350px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-246 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/logo_gsvbw45_q1.jpg\" alt=\"\" width=\"350\" height=\"350\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/logo_gsvbw45_q1.jpg 350w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/logo_gsvbw45_q1-150x150.jpg 150w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/logo_gsvbw45_q1-300x300.jpg 300w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/logo_gsvbw45_q1-100x100.jpg 100w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><figcaption id=\"caption-attachment-246\" class=\"wp-caption-text\">Die Dokumentation der GSVBw 45 befindet sich in unserer Mediathek.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h1>Sturmsch\u00e4den auf dem Gel\u00e4nde der GSVBw 22<\/h1>\n<p>Kr\u00e4ftige St\u00fcrme sorgten auch im Dezember wieder daf\u00fcr, dass ein Baum auf dem Grundst\u00fcck der GSVBw 22 umgest\u00fcrzt ist. Besonders kritisch: Der Baum verfing sich in der Krone eines benachbarten Baumes. Dadurch bestand die Gefahr, dass eine Wetterschutz-\u00dcberdachung durch Bruchholz besch\u00e4digt wird. Mit dem Traktor wurde der Baum vorsichtig aus den Schadensbereich ger\u00fcckt. Eine Gef\u00e4hrdung der denkmalgesch\u00fctzten Bebauung lag somit nicht mehr vor.<\/p>\n<figure id=\"attachment_3867\" aria-describedby=\"caption-attachment-3867\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3867 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_11.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_11.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_11-400x300.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_11-768x576.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-3867\" class=\"wp-caption-text\">Gefahr f\u00fcr den Wetterschutz-\u00dcberbau: Ein Baum ist umgest\u00fcrzt und fiel in der Krone eines benachbarten Baumes.<\/figcaption><\/figure>\n<figure id=\"attachment_3868\" aria-describedby=\"caption-attachment-3868\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3868 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_12.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_12.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_12-400x300.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_12-768x576.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-3868\" class=\"wp-caption-text\">Mit Hilfe des Traktors wurde der umgest\u00fcrzte Baum vorsichtig aus der Baumkrone gezogen.<\/figcaption><\/figure>\n<figure id=\"attachment_3869\" aria-describedby=\"caption-attachment-3869\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3869 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_13.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_13.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_13-400x300.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_13-768x576.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-3869\" class=\"wp-caption-text\">Stellt nun keine Gefahr mehr dar: Der Baum liegt fast am Boden.<\/figcaption><\/figure>\n<figure id=\"attachment_3870\" aria-describedby=\"caption-attachment-3870\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3870 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_14.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_14.jpg 800w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_14-400x300.jpg 400w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_14-768x576.jpg 768w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption id=\"caption-attachment-3870\" class=\"wp-caption-text\">Abschlie\u00dfende Aufr\u00e4umarbeiten auf dem GSVBw-Grundst\u00fcck.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h1>\u00dcberarbeitung des Webseiten-Inhalts &#8222;Zivilschutzanlagen&#8220;<\/h1>\n<p>Neben der praktischen Arbeit im Objekt nimmt auch die Recherche zur GSVBw- und Zivilschutz-Thematik einen gro\u00dfen Bereich in unserer gemeinn\u00fctzigen Vereinsarbeit ein.<\/p>\n<p>Aus Dokumenten, die im Bundesarchiv Koblenz archiviert sind, geht hervor, dass die Zivilschutzanlage in Hannover-Ricklingen zu den bundesweit ersten 34 Anlagen geh\u00f6rte, die im Vorabprogramm f\u00fcr eine Instandsetzung vorgesehen waren. Aufgrund dieser Besonderheit haben wir unseren Themenbereich &#8222;Zivilschutzanlagen&#8220; \u00fcberarbeitet.<\/p>\n<figure id=\"attachment_247\" aria-describedby=\"caption-attachment-247\" style=\"width: 350px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.vorbei-ev.de\/wwwa\/zivilschutzanlagen-einleitung-und-themenuebersicht\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-247 size-full\" src=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/zsa_banner.jpg\" alt=\"\" width=\"350\" height=\"350\" srcset=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/zsa_banner.jpg 350w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/zsa_banner-150x150.jpg 150w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/zsa_banner-300x300.jpg 300w, https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/03\/zsa_banner-100x100.jpg 100w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><figcaption id=\"caption-attachment-247\" class=\"wp-caption-text\">Zu erreichen ist dieser Themenbereich \u00fcber das Bild, \u00fcber den Verweis auf unserer Startseite, oder \u00fcber die Adresse <a href=\"http:\/\/www.zivilschutzanlagen.com\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.zivilschutzanlagen.com<\/a><\/figcaption><\/figure>\n<p>Mit einem Klick auf das Bild gelangt man zum Themenbereich Zivilschutzanlagen.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left shariff-buttonstretch\" data-services=\"facebook\" data-url=\"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/\" data-timestamp=\"1614627461\" data-backendurl=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/shariff\/v1\/share_counts?\"><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.vorbei-ev.de%2Fwwwa%2F2014%2F01%2F11%2Fvereinsaktivitaeten-im-dezember-2013%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.vorbei-ev.de%2Fwwwa%2F2014%2F01%2F11%2Fvereinsaktivitaeten-im-dezember-2013%2F&text=Vereinsaktivit%C3%A4ten%20im%20Dezember%202013\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.vorbei-ev.de%2Fwwwa%2F2014%2F01%2F11%2Fvereinsaktivitaeten-im-dezember-2013%2F%20Vereinsaktivit%C3%A4ten%20im%20Dezember%202013\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button telegram shariff-nocustomcolor\" style=\"background-color:#4084A6\"><a href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.vorbei-ev.de%2Fwwwa%2F2014%2F01%2F11%2Fvereinsaktivitaeten-im-dezember-2013%2F&text=Vereinsaktivit%C3%A4ten%20im%20Dezember%202013\" title=\"Bei Telegram teilen\" aria-label=\"Bei Telegram teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0088cc; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#0088cc\" d=\"M30.8 6.5l-4.5 21.4c-.3 1.5-1.2 1.9-2.5 1.2L16.9 24l-3.3 3.2c-.4.4-.7.7-1.4.7l.5-7L25.5 9.2c.6-.5-.1-.8-.9-.3l-15.8 10L2 16.7c-1.5-.5-1.5-1.5.3-2.2L28.9 4.3c1.3-.5 2.3.3 1.9 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Informations-Faltblatt \u00fcber das Projekt &#8222;Museumsbunker Hannover&#8220; verf\u00fcgbar Aufgrund h\u00e4ufiger Nachfragen haben wir ein Informationsfaltblatt f\u00fcr unser Projekt &#8222;Museumsbunker Hannover&#8220; erstellt. Das Blatt informiert \u00fcber den Projekthintergrund und verdeutlicht die Besonderheiten der Zivilschutzanlage Hannover-Ricklingen. Weiterhin gibt es Eckdaten zu unserem gemeinn\u00fctzigen Verein und zu weiteren Vereinsprojekten. Das Informationsfaltblatt liegt zur Mitnahme in unseren Vereinsanlagen aus. Auch &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eVereinsaktivit\u00e4ten im Dezember 2013\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":3865,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-8650","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-24","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vereinsaktivit\u00e4ten im Dezember 2013 - Vorbei e.V.<\/title>\n<meta name=\"description\" content=\"Wir planen, in der Zivilschutzanlage Hannover-Ricklingen eine Sammlung verschiedener Schutzraum-Bel\u00fcftungsger\u00e4te aufzubauen. Zusammen mit unterschiedlichen Raumfiltermodellen soll so die Entwicklung dieser Ger\u00e4te anschaulich aufgezeigt werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vereinsaktivit\u00e4ten im Dezember 2013 - Vorbei e.V.\" \/>\n<meta property=\"og:description\" content=\"Wir planen, in der Zivilschutzanlage Hannover-Ricklingen eine Sammlung verschiedener Schutzraum-Bel\u00fcftungsger\u00e4te aufzubauen. Zusammen mit unterschiedlichen Raumfiltermodellen soll so die Entwicklung dieser Ger\u00e4te anschaulich aufgezeigt werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/\" \/>\n<meta property=\"og:site_name\" content=\"Vorbei e.V.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/107150626035606\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-11T12:30:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-01T18:37:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lars Knauer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lars Knauer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/\"},\"author\":{\"name\":\"Lars Knauer\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#\\\/schema\\\/person\\\/73a85b6f1e47d7e120f5469e01829e53\"},\"headline\":\"Vereinsaktivit\u00e4ten im Dezember 2013\",\"datePublished\":\"2014-01-11T12:30:19+00:00\",\"dateModified\":\"2021-03-01T18:37:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/\"},\"wordCount\":625,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/image2013-12_03.jpg\",\"articleSection\":[\"2013\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/\",\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/\",\"name\":\"Vereinsaktivit\u00e4ten im Dezember 2013 - Vorbei e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/image2013-12_03.jpg\",\"datePublished\":\"2014-01-11T12:30:19+00:00\",\"dateModified\":\"2021-03-01T18:37:41+00:00\",\"description\":\"Wir planen, in der Zivilschutzanlage Hannover-Ricklingen eine Sammlung verschiedener Schutzraum-Bel\u00fcftungsger\u00e4te aufzubauen. Zusammen mit unterschiedlichen Raumfiltermodellen soll so die Entwicklung dieser Ger\u00e4te anschaulich aufgezeigt werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/image2013-12_03.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/image2013-12_03.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/2014\\\/01\\\/11\\\/vereinsaktivitaeten-im-dezember-2013\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vereinsaktivit\u00e4ten im Dezember 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#website\",\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/\",\"name\":\"Vorbei e.V.\",\"description\":\"Dokumentation und Erhalt zeitgeschichtlicher Bauwerke\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#organization\",\"name\":\"Vorbei e.V.\",\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Logo_schwarz_640px.png\",\"contentUrl\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Logo_schwarz_640px.png\",\"width\":640,\"height\":120,\"caption\":\"Vorbei e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/107150626035606\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/#\\\/schema\\\/person\\\/73a85b6f1e47d7e120f5469e01829e53\",\"name\":\"Lars Knauer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g\",\"caption\":\"Lars Knauer\"},\"url\":\"https:\\\/\\\/www.vorbei-ev.de\\\/wwwa\\\/author\\\/lars\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vereinsaktivit\u00e4ten im Dezember 2013 - Vorbei e.V.","description":"Wir planen, in der Zivilschutzanlage Hannover-Ricklingen eine Sammlung verschiedener Schutzraum-Bel\u00fcftungsger\u00e4te aufzubauen. Zusammen mit unterschiedlichen Raumfiltermodellen soll so die Entwicklung dieser Ger\u00e4te anschaulich aufgezeigt werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/","og_locale":"de_DE","og_type":"article","og_title":"Vereinsaktivit\u00e4ten im Dezember 2013 - Vorbei e.V.","og_description":"Wir planen, in der Zivilschutzanlage Hannover-Ricklingen eine Sammlung verschiedener Schutzraum-Bel\u00fcftungsger\u00e4te aufzubauen. Zusammen mit unterschiedlichen Raumfiltermodellen soll so die Entwicklung dieser Ger\u00e4te anschaulich aufgezeigt werden.","og_url":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/","og_site_name":"Vorbei e.V.","article_publisher":"https:\/\/www.facebook.com\/groups\/107150626035606\/","article_published_time":"2014-01-11T12:30:19+00:00","article_modified_time":"2021-03-01T18:37:41+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03.jpg","type":"image\/jpeg"}],"author":"Lars Knauer","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03.jpg","twitter_misc":{"Verfasst von":"Lars Knauer","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/#article","isPartOf":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/"},"author":{"name":"Lars Knauer","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#\/schema\/person\/73a85b6f1e47d7e120f5469e01829e53"},"headline":"Vereinsaktivit\u00e4ten im Dezember 2013","datePublished":"2014-01-11T12:30:19+00:00","dateModified":"2021-03-01T18:37:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/"},"wordCount":625,"publisher":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#organization"},"image":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03.jpg","articleSection":["2013"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/","url":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/","name":"Vereinsaktivit\u00e4ten im Dezember 2013 - Vorbei e.V.","isPartOf":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/#primaryimage"},"image":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03.jpg","datePublished":"2014-01-11T12:30:19+00:00","dateModified":"2021-03-01T18:37:41+00:00","description":"Wir planen, in der Zivilschutzanlage Hannover-Ricklingen eine Sammlung verschiedener Schutzraum-Bel\u00fcftungsger\u00e4te aufzubauen. Zusammen mit unterschiedlichen Raumfiltermodellen soll so die Entwicklung dieser Ger\u00e4te anschaulich aufgezeigt werden.","breadcrumb":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/#primaryimage","url":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03.jpg","contentUrl":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/05\/image2013-12_03.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/2014\/01\/11\/vereinsaktivitaeten-im-dezember-2013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.vorbei-ev.de\/wwwa\/"},{"@type":"ListItem","position":2,"name":"Vereinsaktivit\u00e4ten im Dezember 2013"}]},{"@type":"WebSite","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#website","url":"https:\/\/www.vorbei-ev.de\/wwwa\/","name":"Vorbei e.V.","description":"Dokumentation und Erhalt zeitgeschichtlicher Bauwerke","publisher":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vorbei-ev.de\/wwwa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#organization","name":"Vorbei e.V.","url":"https:\/\/www.vorbei-ev.de\/wwwa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#\/schema\/logo\/image\/","url":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/04\/Logo_schwarz_640px.png","contentUrl":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-content\/uploads\/2017\/04\/Logo_schwarz_640px.png","width":640,"height":120,"caption":"Vorbei e.V."},"image":{"@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/107150626035606\/"]},{"@type":"Person","@id":"https:\/\/www.vorbei-ev.de\/wwwa\/#\/schema\/person\/73a85b6f1e47d7e120f5469e01829e53","name":"Lars Knauer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c136720ef8906c1f38a1bab0adc43160b1ccd6793f5abe75d6ea003e09b6c569?s=96&d=mm&r=g","caption":"Lars Knauer"},"url":"https:\/\/www.vorbei-ev.de\/wwwa\/author\/lars\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/posts\/8650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/comments?post=8650"}],"version-history":[{"count":1,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/posts\/8650\/revisions"}],"predecessor-version":[{"id":8651,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/posts\/8650\/revisions\/8651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/media\/3865"}],"wp:attachment":[{"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/media?parent=8650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/categories?post=8650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vorbei-ev.de\/wwwa\/wp-json\/wp\/v2\/tags?post=8650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}